{"id":1795,"count":1,"description":"","link":"https:\/\/www.beliteweight.com\/blog\/tag\/how-did-lizzo-lose-weight\/","name":"how did lizzo lose weight","slug":"how-did-lizzo-lose-weight","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.beliteweight.com\/blog\/wp-json\/wp\/v2\/tags\/1795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.beliteweight.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.beliteweight.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.beliteweight.com\/blog\/wp-json\/wp\/v2\/posts?tags=1795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}